{"id":39436,"date":"2024-03-27T15:04:18","date_gmt":"2024-03-27T14:04:18","guid":{"rendered":"https:\/\/old.taggrs.cloud\/?page_id=39436"},"modified":"2024-06-20T09:44:15","modified_gmt":"2024-06-20T07:44:15","slug":"case-study-dunion-online-marketing","status":"publish","type":"page","link":"https:\/\/old.taggrs.cloud\/fr\/case-study-dunion-online-marketing\/","title":{"rendered":"Case study Dunion online marketing"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"39436\" class=\"elementor elementor-39436\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43aa4332 e-flex e-con-boxed e-con e-parent\" data-id=\"43aa4332\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6a3c3040 e-con-full e-flex e-con e-child\" data-id=\"6a3c3040\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e44e8f7 elementor-widget elementor-widget-heading\" data-id=\"4e44e8f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Case : Dunion online marketing<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34509f79 elementor-widget elementor-widget-text-editor\" data-id=\"34509f79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.dunion.nl\/\" target=\"_blank\" rel=\"noopener\">Dunion Online Marketing<\/a> est une agence de marketing compl\u00e8te \u00e0 laquelle vous pouvez vous adresser pour tous vos probl\u00e8mes de marketing en ligne. Qu&#8217;il s&#8217;agisse du positionnement de votre marque ou de votre entreprise ou des aspects li\u00e9s \u00e0 la cr\u00e9ation de sites web et de boutiques en ligne, \u00e0 la conception graphique, au marketing par moteur de recherche, au marketing par courrier \u00e9lectronique, au marketing par les m\u00e9dias sociaux ou \u00e0 la vente par l&#8217;interm\u00e9diaire d&#8217;une ou de plusieurs places de march\u00e9.<\/p>\n<div> <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1361d9ed e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"1361d9ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d82822d elementor-widget elementor-widget-image\" data-id=\"4d82822d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1670\" height=\"300\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Dunion-Logo.png\" class=\"attachment-full size-full wp-image-38668\" alt=\"Logo Dunion marketing\" srcset=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Dunion-Logo.png 1670w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Dunion-Logo-300x54.png 300w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Dunion-Logo-1024x184.png 1024w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Dunion-Logo-768x138.png 768w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Dunion-Logo-1536x276.png 1536w\" sizes=\"(max-width: 1670px) 100vw, 1670px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b3b0844 e-flex e-con-boxed e-con e-parent\" data-id=\"b3b0844\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acbcb1e elementor-testimonial--align-left elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-arrows-yes elementor-invisible elementor-widget elementor-widget-testimonial-carousel\" data-id=\"acbcb1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;2&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:70,&quot;sizes&quot;:[]},&quot;slides_per_view_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;1&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Nous sommes extr\u00eamement reconnaissants \u00e0 TAGGRS de nous avoir aid\u00e9s \u00e0 mettre en \u0153uvre le Server Side Tracking pour nous-m\u00eames et pour nos clients. Le professionnalisme et l'expertise ont fait une diff\u00e9rence significative dans les r\u00e9sultats.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/06\/randy-duin.jpg\" alt=\"Randy Duin | Dunion Online Marketing\n\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Randy Duin  <\/span><span class=\"elementor-testimonial__title\">Dunion Online Marketing<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33e6bc50 e-flex e-con-boxed e-con e-parent\" data-id=\"33e6bc50\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3cc6f931 e-con-full e-flex e-con e-child\" data-id=\"3cc6f931\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13efcd3c elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"13efcd3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"350\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/screen1-opt.png\" class=\"attachment-large size-large wp-image-36609\" alt=\"TAGGRS dashboard container view\" srcset=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/screen1-opt.png 650w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/screen1-opt-300x164.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-812e878 e-con-full e-flex e-con e-child\" data-id=\"812e878\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31460be2 elementor-widget elementor-widget-heading\" data-id=\"31460be2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le dossier<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ad1540b elementor-widget elementor-widget-text-editor\" data-id=\"5ad1540b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aidez \u00e0 mettre en place un portail de gestion dans TAGGRS et \u00e0 configurer le Server Side Tracking pour les domaines suivants.<\/p>\n<ul>\n<li>BandagenSpezialist.de<\/li>\n<li>gants de gardien de but.fr<\/li>\n<li>podobrace.co.uk<\/li>\n<li>podobrace.co.uk<\/li>\n<\/ul>\n<div>En outre, les plateformes sociales et le Server Side de Google Ads doivent \u00eatre mis en place.<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe9a94b elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"fe9a94b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"350\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/screen1-opt.png\" class=\"attachment-large size-large wp-image-36609\" alt=\"TAGGRS dashboard container view\" srcset=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/screen1-opt.png 650w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/screen1-opt-300x164.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32eebec3 e-flex e-con-boxed e-con e-parent\" data-id=\"32eebec3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-201c88b7 e-con-full e-flex e-con e-child\" data-id=\"201c88b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f9f89fc elementor-widget elementor-widget-heading\" data-id=\"3f9f89fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La m\u00e9thode<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-203a3888 elementor-widget elementor-widget-text-editor\" data-id=\"203a3888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour ce faire, les solutions suivantes ont \u00e9t\u00e9 mises en \u0153uvre :<\/p>\n<p><strong>Portail de gestion :<\/strong> Le portail de gestion au sein de TAGGRS a \u00e9t\u00e9 mis en place.<br \/><strong>Plateformes sociales Server Side set :<\/strong> Les plateformes Facebook, Snapchat et TikTok sont des ensembles c\u00f4t\u00e9 serveur.<br \/><strong>TAGGRS Tracking Tags :<\/strong> Pour mesurer la diff\u00e9rence entre les conteneurs Web et les conteneurs de serveur, nous avons configur\u00e9 les TAGGRS Tracking Tags.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14a9f78e e-con-full e-flex e-con e-child\" data-id=\"14a9f78e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-198db86f elementor-widget elementor-widget-image\" data-id=\"198db86f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1115\" height=\"963\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/taggrs-dashboard-server-side-analytics-1.png\" class=\"attachment-full size-full wp-image-39249\" alt=\"Dunion TAGGRS dashboard\" srcset=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/taggrs-dashboard-server-side-analytics-1.png 1115w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/taggrs-dashboard-server-side-analytics-1-300x259.png 300w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/taggrs-dashboard-server-side-analytics-1-1024x884.png 1024w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/taggrs-dashboard-server-side-analytics-1-768x663.png 768w\" sizes=\"(max-width: 1115px) 100vw, 1115px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e2c35b9 e-flex e-con-boxed e-con e-parent\" data-id=\"4e2c35b9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3b98dc29 e-con-full e-flex e-con e-child\" data-id=\"3b98dc29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ba5e022 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"2ba5e022\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"181\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case-1024x289.png\" class=\"attachment-large size-large wp-image-39268\" alt=\"resultaat 1 Dunion case\" srcset=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case-1024x289.png 1024w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case-300x85.png 300w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case-768x217.png 768w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case.png 1439w\" sizes=\"(max-width: 640px) 100vw, 640px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2376dc3 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"2376dc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"159\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case-1024x254.png\" class=\"attachment-large size-large wp-image-39263\" alt=\"Resultaat 2 Dunion case\" srcset=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case-1024x254.png 1024w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case-300x74.png 300w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case-768x190.png 768w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case.png 1444w\" sizes=\"(max-width: 640px) 100vw, 640px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-503aa04 e-con-full e-flex e-con e-child\" data-id=\"503aa04\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6bb11344 elementor-widget elementor-widget-heading\" data-id=\"6bb11344\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le r\u00e9sultat  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55ee336a elementor-widget elementor-widget-text-editor\" data-id=\"55ee336a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Portail de gestion :<\/strong> Le portail de gestion a \u00e9t\u00e9 mis en place et les diff\u00e9rents conteneurs des domaines mis en place sont visibles.<br \/><strong>Configuration des domaines par Server Side :<\/strong> Apr\u00e8s la configuration des domaines c\u00f4t\u00e9 serveur, le Dashboard de TAGGRS montre qu&#8217;entre 10 et 30 % de donn\u00e9es suppl\u00e9mentaires sont collect\u00e9es.<br \/><strong>Plateformes sociales :<\/strong> Les Meta Ads &#8211; CAPI montrent l&#8217;arriv\u00e9e de donn\u00e9es Server Side.<\/p>\n<p>Vous pouvez voir sur la droite 2 Events mesur\u00e9s par le pixel Meta-pixel dans les graphes vous pouvez clairement voir la diff\u00e9rence entre les mesures par le navigateur et les mesures par le serveur. La ligne verte correspond aux events du server et la ligne bleue aux events du browser. Dans cet exemple, cela se traduit par 22 % de donn\u00e9es suppl\u00e9mentaires.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47f339f elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"47f339f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"181\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case-1024x289.png\" class=\"attachment-large size-large wp-image-39268\" alt=\"resultaat 1 Dunion case\" srcset=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case-1024x289.png 1024w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case-300x85.png 300w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case-768x217.png 768w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/resultaat-1-Dunion-case.png 1439w\" sizes=\"(max-width: 640px) 100vw, 640px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-517d577 elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"517d577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"159\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case-1024x254.png\" class=\"attachment-large size-large wp-image-39263\" alt=\"Resultaat 2 Dunion case\" srcset=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case-1024x254.png 1024w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case-300x74.png 300w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case-768x190.png 768w, https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Resultaat-2-Dunion-case.png 1444w\" sizes=\"(max-width: 640px) 100vw, 640px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b9b144 e-flex e-con-boxed e-con e-parent\" data-id=\"6b9b144\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4b9698 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f4b9698\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ce que disent les clients<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9a90ca elementor-testimonial--align-left elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-arrows-yes elementor-invisible elementor-widget elementor-widget-testimonial-carousel\" data-id=\"c9a90ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;2&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:70,&quot;sizes&quot;:[]},&quot;slides_per_view_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;1&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Enfin, une bonne installation de suivi compl\u00e8te. J'ai obtenu plus de donn\u00e9es pour mes campagnes Google Ads et je vois maintenant chacune de mes commandes rapport\u00e9es avec pr\u00e9cision dans GA4.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/01\/orlqtiD2kqjIsJox1IoSSgdKNesGJgupwU50JznG.png\" alt=\"PPC Mastery logo\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Bob Meijer<\/span><span class=\"elementor-testimonial__title\">PPC Mastery<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>TAGGRS offre une excellente solution de suivi c\u00f4t\u00e9 serveur. Ils disposent d'un tableau de bord int\u00e9ressant o\u00f9 l'on peut voir l'augmentation de la quantit\u00e9 de donn\u00e9es mesur\u00e9es gr\u00e2ce au suivi c\u00f4t\u00e9 serveur par rapport au suivi c\u00f4t\u00e9 client. Mais la meilleure chose est leur support : toutes vos questions techniques sont r\u00e9pondues en moins de 3 minutes via le chat en direct. 11\/10 bravo !<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Lowie-Verschelden-review-jpeg.webp\" alt=\"Lowie Verschelden\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Lowie Verschelden<\/span><span class=\"elementor-testimonial__title\">Marketing num\u00e9rique freelance<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Bonne exp\u00e9rience avec TAGGRS pour la mise en place du GTM side serveur pour GA4 et Meta. Tout est bien organis\u00e9, la communication est bonne et fluide. Toppers !<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2023\/07\/photo.jpg.png\" alt=\"Marnix Vos\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Marnix Vos<\/span><span class=\"elementor-testimonial__title\">Vos marketing<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Le cofondateur Niek a fourni une assistance client\u00e8le fantastique. Plateforme bien faite, claire, moderne et surtout 100% conforme au GDPR. Je recommanderais ce service aux agences de marketing, nouvelles ou existantes, pour la collecte\/le suivi des donn\u00e9es. TAGGERS propose \u00e9galement un plan gratuit pour commencer ! \ud83d\ude42<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2023\/07\/63fb840be258eafa0f25e6f4.png.webp\" alt=\"Logo Annonsering AS.png\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Nikolai Tusvik Hjelle<\/span><span class=\"elementor-testimonial__title\">Annonsering AS<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Nous sommes tr\u00e8s satisfaits de TAGGRS, de ses documents de mise en \u0153uvre clairs et de la valeur ajout\u00e9e du Server Side Tracking !<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2023\/11\/f08f53b77f.png\" alt=\"Vincent Mertens\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Vincent Mertens<\/span><span class=\"elementor-testimonial__title\">Impact Media Concepts<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>La mesurabilit\u00e9 de nos campagnes en ligne devenait de plus en plus impr\u00e9cise. Depuis l'introduction du Server Side Tracking, nous mesurons \u00e0 nouveau toutes les conversions. Cela nous permet non seulement d'assurer un meilleur suivi, mais aussi d'augmenter le retour sur investissement des campagnes. Le TAGGRS nous a beaucoup aid\u00e9s \u00e0 cet \u00e9gard.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2022\/12\/annemieke-kok.jpeg\" alt=\"Annemieke Kok Jeen Marketing\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Annemieke Kok<\/span><span class=\"elementor-testimonial__title\">Communication JEEN<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Nous sommes tr\u00e8s satisfaits de TAGGRS. Ils aident \u00e0 la transition et \u00e0 la mise en \u0153uvre si n\u00e9cessaire, en continuant jusqu'\u00e0 ce que tout fonctionne parfaitement. Nous disposons de donn\u00e9es \u00e0 la fois plus nombreuses et plus pr\u00e9cises, ce qui va nous aider dans l'analyse et la prise de d\u00e9cision. Nous recommandons \u00e0 tout le monde d'utiliser TAGGRS !<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/01\/Scherm\u00adafbeelding-2024-01-09-om-14.36.26.png\" alt=\"Sp\u00e9cialiste Google Shopping\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Sp\u00e9cialiste Google Shopping<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Le service est excellent : prix int\u00e9ressants, facilit\u00e9 d'installation, excellent support client si quelque chose ne fonctionne pas comme pr\u00e9vu (pendant les heures de travail, cela n'a pris que 5 minutes). Recommandation compl\u00e8te !<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Tim-Glockemann-review.png\" alt=\"Tim Glockemann\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Tim Glockemann<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Tr\u00e8s bon contact avec les messieurs de TAGGRS, rapide et direct. Il est simple \u00e0 mettre en place et \u00e0 utiliser, \u00e0 des prix tr\u00e8s raisonnables.<br \/>\nTout \u00e0 fait recommand\u00e9<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2024\/03\/Mark-Bakker-google-review.png\" alt=\"Mark Bakker google review\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Mark Bakker<\/span><span class=\"elementor-testimonial__title\">GoogleShoppingSpecialist.co.uk<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Exp\u00e9rience positive avec TAGGRS. Niels a mis en place le Server Side Tracking pour notre entreprise. Tout s'est d\u00e9roul\u00e9 sans probl\u00e8me et tout est bien rang\u00e9. Actuellement, nous obtenons plus de 20 % de donn\u00e9es suppl\u00e9mentaires gr\u00e2ce au Server Side Tracking. La communication est bonne et, en cas de probl\u00e8me, les files d'attente sont courtes. Top !<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2023\/04\/berghof-logo.png\" alt=\"berghof-logo\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Kevin Verhaaf<\/span><span class=\"elementor-testimonial__title\">Berghofmembranes<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>''Depuis la mise en \u0153uvre du Server Side Tracking, je constate une diff\u00e9rence positive dans le nombre de conversions de ma campagne Facebook en cours. En ajoutant l'API Conversion, je peux obtenir plus de donn\u00e9es dans Facebook, ce qui a aid\u00e9 les campagnes \u00e0 mieux fonctionner.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/old.taggrs.cloud\/wp-content\/uploads\/2022\/12\/femke-pepers.jpeg\" alt=\"Femke Peppers\" title=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Femke Peppers<\/span><span class=\"elementor-testimonial__title\">En forme avec Femke<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56f98713 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"56f98713\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1f773183 e-con-full e-flex e-con e-child\" data-id=\"1f773183\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78e52095 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"78e52095\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Serez-vous notre prochain cas ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16052ad4 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"16052ad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lancez Server Side Tracking et g\u00e9n\u00e9rez plus de ventes et de conversions dans un monde sans cookies tiers.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-218d0333 elementor-align-left elementor-widget__width-inherit elementor-mobile-align-justify elementor-invisible elementor-widget elementor-widget-button\" data-id=\"218d0333\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/app.taggrs.io\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Commencer gratuitement<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Case : Dunion online marketing Dunion Online Marketing est une agence de marketing compl\u00e8te \u00e0 laquelle vous pouvez vous adresser pour tous vos probl\u00e8mes de marketing en ligne. Qu&#8217;il s&#8217;agisse du positionnement de votre marque ou de votre entreprise ou des aspects li\u00e9s \u00e0 la cr\u00e9ation de sites web et de boutiques en ligne, \u00e0 &#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-39436","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/old.taggrs.cloud\/fr\/wp-json\/wp\/v2\/pages\/39436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.taggrs.cloud\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/old.taggrs.cloud\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/old.taggrs.cloud\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/old.taggrs.cloud\/fr\/wp-json\/wp\/v2\/comments?post=39436"}],"version-history":[{"count":0,"href":"https:\/\/old.taggrs.cloud\/fr\/wp-json\/wp\/v2\/pages\/39436\/revisions"}],"wp:attachment":[{"href":"https:\/\/old.taggrs.cloud\/fr\/wp-json\/wp\/v2\/media?parent=39436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}